{"id":11689,"date":"2017-05-24T16:54:57","date_gmt":"2017-05-24T14:54:57","guid":{"rendered":"http:\/\/lyonbondyblog.fr\/LBB\/?p=11689"},"modified":"2017-05-26T10:22:51","modified_gmt":"2017-05-26T08:22:51","slug":"legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne","status":"publish","type":"post","link":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/","title":{"rendered":"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne."},"content":{"rendered":"<p><em>Dix jours apr\u00e8s l\u2019\u00e9lection d\u2019Emmanuel Macron \u00e0 la pr\u00e9sidence de la R\u00e9publique Fran\u00e7aise et de la mise en place de son nouveau gouvernement, la vie politique se tourne d\u00e9sormais vers les \u00e9lections l\u00e9gislatives. &nbsp;Le mercredi 17 mai s\u2019est tenu le premier \u00ab&nbsp;grand d\u00e9bat&nbsp;\u00bb des l\u00e9gislatives 2017 entre les candidats de la 6<sup>\u00e8me<\/sup> circonscription de Villeurbanne au Lyon Bondy Blog. Retour sur les moments forts de cette soir\u00e9e.<\/em><\/p>\n<p>Ils \u00e9taient huit pr\u00e9tendants \u00e0 la d\u00e9putation de l\u2019Assembl\u00e9e Nationale \u00e0 \u00eatre pr\u00e9sents mercredi soir au Lyon Bondy Blog, pour le premier d\u00e9bat des l\u00e9gislatives 2017. Parmi eux, Beatrice Vessiller du parti Europe Ecologie les Verts, Camille Chauchat du NPA (Nouveau Parti Anticapitaliste), Emmanuelle Haziza de Les R\u00e9publicains, Laurent Legendre de France Insoumise, St\u00e9phane Poncet du Front National, Herv\u00e9 Morel du Centre Ind\u00e9pendant, Mathieu Suarez du PCF (Parti Communiste Fran\u00e7ais), et Claire Lainez de Lutte Ouvri\u00e8re. A travers les th\u00e8mes de l\u2019\u00e9ducation, l\u2019emploi, la s\u00e9curit\u00e9 ou encore l\u2019environnement, les candidats se sont chacun exprim\u00e9s avec le respect du temps de parole qui leur ont \u00e9t\u00e9 accord\u00e9. Pendant pr\u00e8s de deux heures, ils se sont positionn\u00e9s dans une ambiance quelque peu solennelle en exposant tour \u00e0 tour les divers projets de leur programme.<\/p>\n<p>Sur le th\u00e8me de l\u2019\u00e9ducation chaque candidat \u00e9tait en ad\u00e9quation pour dire qu\u2019il y avait des progr\u00e8s \u00e0 faire notamment concernant les classes surcharg\u00e9es. Probl\u00e8mes au niveau de nombre de professeurs et dans la p\u00e9dagogie pour Camille Chauchat. Poncet, de son c\u00f4t\u00e9, estime qu\u2019il y a un retard \u00e0 rattraper reprochant \u00e0 la nouvelle p\u00e9dagogie scolaire d&rsquo;\u00eatre&nbsp;arri\u00e9r\u00e9e. La fuite vers le priv\u00e9 \u00e0 un impact dans le public. La candidate de Lutte Ouvri\u00e8re, Claire Lainez trouve elle, qu\u2019il faudrait mettre davantage d&rsquo;efforts dans l\u2019embauche de plus d&rsquo;enseignants.<\/p>\n<p>Concernant l\u2019am\u00e9nagement scolaire, la question du rythme scolaire a suscit\u00e9 pas mal de d\u00e9sapprobations. Le candidat du Centre Ind\u00e9pendant, Herv\u00e9 Morel, \u00e9voque une r\u00e9forme b\u00e2cl\u00e9e, avec un syst\u00e8me p\u00e9riscolaire \u00e0 mettre en pratique. L\u2019important c\u2019est de prendre en compte la situation des parents. Pour Laurent Legendre, de France Insoumise, la question du temps de travail pose \u00e9norm\u00e9ment de probl\u00e8me. Une des priorit\u00e9s de son programme concernant l\u2019\u00e9ducation : instaurer une cantine gratuite et surtout biologique. Les journ\u00e9es d\u2019\u00e9tude \u00e9tant consid\u00e9r\u00e9es comme trop longue, Beatrice Vessiller estime qu\u2019il serait judicieux de r\u00e9duire le temps de travail \u00e0 32h par semaine.<\/p>\n<p>Deuxi\u00e8me th\u00e8me de la soir\u00e9e&nbsp;: l\u2019emploi, dont le plus gros point noir reste, le ch\u00f4mage. Inverser la courbe du ch\u00f4mage reste le grand challenge de tout gouvernement depuis 2012. Mais avant toute chose, l\u2019acc\u00e8s \u00e0 l\u2019emploi et la discrimination reste n\u00e9anmoins des facteurs majeurs tr\u00e8s pr\u00e9sents dans notre soci\u00e9t\u00e9. Emmanuelle Haziza estime que la discrimination \u00e0 l\u2019embauche est devenue malheureusement une g\u00e9n\u00e9ralit\u00e9, une mise en place de r\u00e9elles sanctions serait n\u00e9cessaire. Encourager les pratiques de \u00ab&nbsp;testing&nbsp;\u00bb (une forme d\u2019exp\u00e9rimentation sociale en situation r\u00e9elle destin\u00e9e \u00e0 d\u00e9celer une situation de discrimination) li\u00e9es \u00e0 l\u2019embauche serait plus judicieux pour la candidate d\u2019EE-LV, Beatrice Vessiller. Elle estime notamment qu\u2019il faudrait mettre en lumi\u00e8re les entreprises et lutter contre toute discrimination. Pour Mathieu Suarez, il faudrait un travail des discriminations \u00e0 l\u2019int\u00e9rieur et \u00e0 l\u2019ext\u00e9rieur dans entreprises afin d\u2019y int\u00e9grer au bilan social, une annexe sur les discriminations. Les travailleurs doivent \u00eatre rassembl\u00e9s proclame Claire Lainez.<\/p>\n<p>Arriv\u00e9e \u00e0 la partie concernant le ch\u00f4mage, ce dernier n\u2019est que le r\u00e9sultat d\u2019une condition de travail qui s\u2019est perp\u00e9tuellement d\u00e9grad\u00e9 estime toujours la candidate de Lutte Ouvri\u00e8re. <em>\u00ab\u00a0Le travail rapporte, il faut arr\u00eater de licencier \u00e0 tout va\u00a0\u00bb<\/em>. Pour le NPA, repr\u00e9sent\u00e9 par Camille Chauchat, les travailleurs manquent cruellement de reconnaissance. La souffrance des travailleurs est telle que cette courbe du ch\u00f4mage n\u2019est pas une surprise. Mathieu Suarez voit l\u2019importance dans la s\u00e9curisation de l\u2019emploi, car le travaille est un vecteur d\u2019\u00e9mancipation et il faut davantage privil\u00e9gier cet aspect. <em>\u00ab\u00a0Rendre l\u2019argent utile\u00a0\u00bb<\/em>. Le partage du temps de travail est une priorit\u00e9 pour Laurent Legendre de France Insoumise. Il faut mettre un projet \u00e9co-socialiste en transformant les traites lib\u00e9rales et en changeant les \u00e9nergies fossiles.<\/p>\n<p>Une premi\u00e8re partie pour le moins, bien anim\u00e9e, o\u00f9 chaque candidat a d\u00e9fendu bec et ongles ses id\u00e9es et ses convictions. Un engagement prononc\u00e9 qu\u2019on retrouvera dans la deuxi\u00e8me partie du d\u00e9bat\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Lien du d\u00e9bat&nbsp; : https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-debat-villeurbanne\/<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dix jours apr\u00e8s l\u2019\u00e9lection d\u2019Emmanuel Macron \u00e0 la pr\u00e9sidence de la R\u00e9publique Fran\u00e7aise et de la mise en place de son nouveau gouvernement, la vie &hellip; <!-- AddThis Advanced Settings generic via filter on wp_trim_excerpt --><!-- AddThis Share Buttons generic via filter on wp_trim_excerpt --><\/p>\n","protected":false},"author":796,"featured_media":11692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[2762,6],"tags":[347,348,165,128],"class_list":["post-11689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislative-2017","category-politique","tag-candidat","tag-legislative","tag-politique-2","tag-villeurbanne"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne. - Lyon Bondy Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne. - Lyon Bondy Blog\" \/>\n<meta property=\"og:description\" content=\"Dix jours apr\u00e8s l\u2019\u00e9lection d\u2019Emmanuel Macron \u00e0 la pr\u00e9sidence de la R\u00e9publique Fran\u00e7aise et de la mise en place de son nouveau gouvernement, la vie &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\" \/>\n<meta property=\"og:site_name\" content=\"Lyon Bondy Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lyonbondyblog\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-24T14:54:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-26T08:22:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png\" \/>\n\t<meta property=\"og:image:width\" content=\"490\" \/>\n\t<meta property=\"og:image:height\" content=\"538\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Mounia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bondybloglyon\" \/>\n<meta name=\"twitter:site\" content=\"@bondybloglyon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\"},\"author\":{\"name\":\"Damien Mounia\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/person\/e0664459beb8b5131a5e83431d89e514\"},\"headline\":\"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne.\",\"datePublished\":\"2017-05-24T14:54:57+00:00\",\"dateModified\":\"2017-05-26T08:22:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\"},\"wordCount\":843,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#organization\"},\"image\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png\",\"keywords\":[\"candidat\",\"l\u00e9gislative\",\"politique\",\"Villeurbanne\"],\"articleSection\":[\"Legislative 2017\",\"Politique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\",\"url\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\",\"name\":\"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne. - Lyon Bondy Blog\",\"isPartOf\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png\",\"datePublished\":\"2017-05-24T14:54:57+00:00\",\"dateModified\":\"2017-05-26T08:22:51+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage\",\"url\":\"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png\",\"contentUrl\":\"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png\",\"width\":490,\"height\":538},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#website\",\"url\":\"https:\/\/lyonbondyblog.fr\/LBB\/\",\"name\":\"Lyon Bondy Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lyonbondyblog.fr\/LBB\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#organization\",\"name\":\"LYON BONDY BLOG\",\"url\":\"https:\/\/lyonbondyblog.fr\/LBB\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2014\/10\/logo-portable-144.png\",\"contentUrl\":\"http:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2014\/10\/logo-portable-144.png\",\"width\":144,\"height\":123,\"caption\":\"LYON BONDY BLOG\"},\"image\":{\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lyonbondyblog\",\"https:\/\/x.com\/bondybloglyon\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/person\/e0664459beb8b5131a5e83431d89e514\",\"name\":\"Damien Mounia\",\"url\":\"https:\/\/lyonbondyblog.fr\/LBB\/author\/damien-mounia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne. - Lyon Bondy Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne. - Lyon Bondy Blog","og_description":"Dix jours apr\u00e8s l\u2019\u00e9lection d\u2019Emmanuel Macron \u00e0 la pr\u00e9sidence de la R\u00e9publique Fran\u00e7aise et de la mise en place de son nouveau gouvernement, la vie &hellip;","og_url":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/","og_site_name":"Lyon Bondy Blog","article_publisher":"https:\/\/www.facebook.com\/lyonbondyblog","article_published_time":"2017-05-24T14:54:57+00:00","article_modified_time":"2017-05-26T08:22:51+00:00","og_image":[{"width":490,"height":538,"url":"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png","type":"image\/png"}],"author":"Damien Mounia","twitter_card":"summary_large_image","twitter_creator":"@bondybloglyon","twitter_site":"@bondybloglyon","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#article","isPartOf":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/"},"author":{"name":"Damien Mounia","@id":"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/person\/e0664459beb8b5131a5e83431d89e514"},"headline":"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne.","datePublished":"2017-05-24T14:54:57+00:00","dateModified":"2017-05-26T08:22:51+00:00","mainEntityOfPage":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/"},"wordCount":843,"commentCount":0,"publisher":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/#organization"},"image":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage"},"thumbnailUrl":"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png","keywords":["candidat","l\u00e9gislative","politique","Villeurbanne"],"articleSection":["Legislative 2017","Politique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/","url":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/","name":"L\u00e9gislatives 2017 : ce qu\u2019il faut retenir du d\u00e9bat tr\u00e8s d\u00e9mocratique de la 6\u00e8me circonscription de Villeurbanne. - Lyon Bondy Blog","isPartOf":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage"},"image":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage"},"thumbnailUrl":"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png","datePublished":"2017-05-24T14:54:57+00:00","dateModified":"2017-05-26T08:22:51+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lyonbondyblog.fr\/LBB\/legislatives-2017-quil-faut-retenir-debat-tres-democratique-de-6eme-circonscription-de-villeurbanne\/#primaryimage","url":"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png","contentUrl":"https:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2017\/05\/18678818_263786507418993_216460109_n.png","width":490,"height":538},{"@type":"WebSite","@id":"https:\/\/lyonbondyblog.fr\/LBB\/#website","url":"https:\/\/lyonbondyblog.fr\/LBB\/","name":"Lyon Bondy Blog","description":"","publisher":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lyonbondyblog.fr\/LBB\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/lyonbondyblog.fr\/LBB\/#organization","name":"LYON BONDY BLOG","url":"https:\/\/lyonbondyblog.fr\/LBB\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/logo\/image\/","url":"http:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2014\/10\/logo-portable-144.png","contentUrl":"http:\/\/lyonbondyblog.fr\/LBB\/wp-content\/uploads\/2014\/10\/logo-portable-144.png","width":144,"height":123,"caption":"LYON BONDY BLOG"},"image":{"@id":"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lyonbondyblog","https:\/\/x.com\/bondybloglyon"]},{"@type":"Person","@id":"https:\/\/lyonbondyblog.fr\/LBB\/#\/schema\/person\/e0664459beb8b5131a5e83431d89e514","name":"Damien Mounia","url":"https:\/\/lyonbondyblog.fr\/LBB\/author\/damien-mounia\/"}]}},"_links":{"self":[{"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/posts\/11689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/users\/796"}],"replies":[{"embeddable":true,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/comments?post=11689"}],"version-history":[{"count":6,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/posts\/11689\/revisions"}],"predecessor-version":[{"id":11719,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/posts\/11689\/revisions\/11719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/media\/11692"}],"wp:attachment":[{"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/media?parent=11689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/categories?post=11689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lyonbondyblog.fr\/LBB\/wp-json\/wp\/v2\/tags?post=11689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}